{"id":2134,"date":"2021-07-22T12:40:02","date_gmt":"2021-07-22T09:40:02","guid":{"rendered":"https:\/\/halkidonioplus.com\/ellinika-os-defteri-glossa-gia-enilikes\/"},"modified":"2024-08-03T12:13:07","modified_gmt":"2024-08-03T09:13:07","slug":"griechischkurse-fuer-jugendliche-und-erwachsene","status":"publish","type":"page","link":"https:\/\/halkidonioplus.com\/de\/griechischkurse-fuer-jugendliche-und-erwachsene\/","title":{"rendered":"Griechischkurse f\u00fcr Jugendliche und Erwachsene"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;0px||50px||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_line_height=&#8220;2em&#8220; text_orientation=&#8220;center&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<p>\u201c\u0392richst du auf gen Ithaka,<br \/>so w\u00fcnsch dir eine lange Fahrt,<br \/>voller Abenteuer und Erkenntnisse\u201d<br \/><strong>\u2014K.P.Kavafis<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]Lernen Sie Griechisch einfach und effektiv. <em>HalkidonioPlus<\/em> bietet online Griechischkurse an und steht Ihnen zur Verf\u00fcgung, um Sie durch die griechische Sprache mit der griechischen Kultur und Geschichte vertraut zu machen. Bereits von Anfang an, sprechen, lesen, schreiben und kommunizieren die Lernenden in der Griechischen Sprache.<\/p>\n<p>HalkidonioPlus ist eine online Fremdsprachenschule und ein ganz besonderer Ort Griechischlernende aus aller Welt zu treffen und sich mit ihnen zu vernetzen. Unsere online Griechischkurse decken alle Niveaustufen der Sprachqualifikationen A1 (Anf\u00e4gerkurs) \u2013 C2 (Oberstufe) ab.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|600|||||||&#8220; text_text_color=&#8220;#FFFFFF&#8220; text_font_size=&#8220;2rem&#8220; text_line_height=&#8220;1.5em&#8220; header_3_font=&#8220;|700|||||||&#8220; header_3_text_align=&#8220;left&#8220; header_3_text_color=&#8220;#FFFFFF&#8220; header_3_font_size=&#8220;1.5rem&#8220; background_color=&#8220;#1688be&#8220; custom_margin=&#8220;||||false|false&#8220; custom_padding=&#8220;10px|20px|13px|20px|false|true&#8220; hover_enabled=&#8220;0&#8243; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<p>Griechishkurse 2024\/25<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;10px||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_blurb title=&#8220;Kostenlose Anmeldung zu allen Kursen&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x4e;||divi||400&#8243; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;30px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;|700|||||||&#8220; header_text_align=&#8220;left&#8220; header_font_size=&#8220;1rem&#8220; header_line_height=&#8220;1.5em&#8220; custom_margin=&#8220;|auto|10px|auto|false|true&#8220; custom_padding=&#8220;||||false|false&#8220; animation=&#8220;off&#8220; custom_css_blurb_image=&#8220;position: relative;||top: -5px;&#8220; icon_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_blurb][et_pb_blurb title=&#8220;Kostenloser erster Probeunterricht*&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x4e;||divi||400&#8243; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;30px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;|700|||||||&#8220; header_text_align=&#8220;left&#8220; header_font_size=&#8220;1rem&#8220; header_line_height=&#8220;1.5em&#8220; custom_margin=&#8220;|auto|10px|auto|false|true&#8220; animation=&#8220;off&#8220; custom_css_blurb_image=&#8220;position: relative;||top: -5px;&#8220; icon_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_blurb][et_pb_blurb use_icon=&#8220;on&#8220; font_icon=&#8220;&#x4e;||divi||400&#8243; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;30px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;|700|||||||&#8220; header_text_align=&#8220;left&#8220; header_font_size=&#8220;1rem&#8220; header_line_height=&#8220;1.5em&#8220; body_font=&#8220;|700|||||||&#8220; body_link_font=&#8220;|700|||||||&#8220; body_link_text_color=&#8220;#1688be&#8220; custom_margin=&#8220;|auto|10px|auto|false|true&#8220; animation=&#8220;off&#8220; custom_css_blurb_image=&#8220;position: relative;||top: -5px;&#8220; icon_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]Kostenloser Einstufungstest (<a href=\"https:\/\/halkidonioplus.com\/de\/register\/griechischkurse-fuer-jugendliche-und-erwachsene-kostenloser-einstufungstest\/\">hier klicken<\/a>)[\/et_pb_blurb][et_pb_blurb title=&#8220;Zugang zu kostenlosen interaktiven digitalen Hilfsmitteln, Online-\u00dcbungen zum H\u00f6rverstehen, Videos, Apps, Filmen, Musik und Spielen, die den Unterrichtsstoff auf angenehme Art und Weise erg\u00e4nzen und Motivation zum Lernen \u00fcbermitteln.&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x4e;||divi||400&#8243; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;30px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;|700|||||||&#8220; header_text_align=&#8220;left&#8220; header_font_size=&#8220;1rem&#8220; header_line_height=&#8220;1.5em&#8220; custom_margin=&#8220;|auto|10px|auto|false|true&#8220; animation=&#8220;off&#8220; custom_css_blurb_image=&#8220;position: relative;||top: -5px;&#8220; icon_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;10px||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|600|||||||&#8220; text_text_color=&#8220;#FFFFFF&#8220; text_font_size=&#8220;1.5rem&#8220; text_line_height=&#8220;1.5em&#8220; background_color=&#8220;#1688be&#8220; custom_padding=&#8220;10px|20px|13px|20px|false|true&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]Allgemeines Griechischkurse[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;20px||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#f9ede1&#8243; custom_padding=&#8220;||40px||false|false&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|700|||||||&#8220; text_text_color=&#8220;#FFFFFF&#8220; text_font_size=&#8220;1.25rem&#8220; text_line_height=&#8220;2em&#8220; background_color=&#8220;#476647&#8243; text_orientation=&#8220;center&#8220; custom_padding=&#8220;20px|20px|20px|20px|true|false&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<p>A1-A2<br \/>2 Stunden\/Woche<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; text_line_height=&#8220;2em&#8220; header_5_font=&#8220;|700|||||||&#8220; header_5_text_color=&#8220;#1688be&#8220; header_5_font_size=&#8220;1.25rem&#8220; custom_padding=&#8220;10px|40px|10px|40px|false|true&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<p><strong>Vormittags und Nachmittagskurs<\/strong><\/p>\n<h5 style=\"padding-top: 25px;\">99\u20ac monatlich<\/h5>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;https:\/\/halkidonioplus.com\/de\/register\/griechischkurse-fuer-jugendliche-und-erwachsene-intensivkurs-a1-a2-kostenlose-testversion\/&#8220; button_text=&#8220;Kostenlose Testversion&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;20px&#8220; button_bg_color=&#8220;#e8168a&#8220; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;10px&#8220; button_letter_spacing=&#8220;0.5px&#8220; button_font=&#8220;|600|||||||&#8220; button_use_icon=&#8220;off&#8220; background_layout=&#8220;dark&#8220; global_colors_info=&#8220;{}&#8220; button_bg_color__hover_enabled=&#8220;on|hover&#8220; button_bg_color__hover=&#8220;#bf1272&#8243; button_bg_enable_color__hover=&#8220;on&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; background_enable_color=&#8220;off&#8220; custom_padding=&#8220;||40px||false|false&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#f9ede1&#8243; custom_padding=&#8220;||40px||false|false&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|700|||||||&#8220; text_text_color=&#8220;#FFFFFF&#8220; text_font_size=&#8220;1.25rem&#8220; text_line_height=&#8220;2em&#8220; background_color=&#8220;#e66432&#8243; text_orientation=&#8220;center&#8220; custom_padding=&#8220;20px|20px|20px|20px|true|false&#8220; hover_enabled=&#8220;0&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<p>Niveau B1<br \/>2 Stunden\/Woche<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; text_line_height=&#8220;2em&#8220; header_5_font=&#8220;|700|||||||&#8220; header_5_text_color=&#8220;#1688be&#8220; header_5_font_size=&#8220;1.25rem&#8220; custom_padding=&#8220;10px|40px|10px|40px|false|true&#8220; hover_enabled=&#8220;0&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<p><strong>Vormittags und Nachmittagskurs<\/strong><\/p>\n<h5 style=\"padding-top: 25px;\">99\u20ac monatlich<\/h5>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;https:\/\/halkidonioplus.com\/de\/register\/griechischkurse-fuer-jugendliche-und-erwachsene-niveau-b1-kostenlose-testversion\/&#8220; button_text=&#8220;Kostenlose Testversion&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;20px&#8220; button_bg_color=&#8220;#e8168a&#8220; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;10px&#8220; button_letter_spacing=&#8220;0.5px&#8220; button_font=&#8220;|600|||||||&#8220; button_use_icon=&#8220;off&#8220; background_layout=&#8220;dark&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; button_bg_color__hover_enabled=&#8220;on|hover&#8220; button_bg_color__hover=&#8220;#bf1272&#8243; button_bg_enable_color__hover=&#8220;on&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#f9ede1&#8243; custom_padding=&#8220;||40px||false|false&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|700|||||||&#8220; text_text_color=&#8220;#FFFFFF&#8220; text_font_size=&#8220;1.25rem&#8220; text_line_height=&#8220;2em&#8220; background_color=&#8220;#800c4c&#8220; text_orientation=&#8220;center&#8220; custom_padding=&#8220;20px|20px|20px|20px|true|false&#8220; hover_enabled=&#8220;0&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<p>Niveau B2<br \/>3 Stunden\/Woche<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_line_height=&#8220;2em&#8220; header_5_font=&#8220;|700|||||||&#8220; header_5_text_color=&#8220;#1688be&#8220; header_5_font_size=&#8220;1.25rem&#8220; custom_padding=&#8220;10px|40px|10px|40px|false|true&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<p><strong>Vormittags und Nachmittagskurs<\/strong><\/p>\n<h5 style=\"padding-top: 25px;\">139\u20ac monatlich<\/h5>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;https:\/\/halkidonioplus.com\/de\/register\/griechischkurse-fuer-jugendliche-und-erwachsene-niveau-b2-kostenlose-testversion\/&#8220; button_text=&#8220;Kostenlose Testversion&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;20px&#8220; button_bg_color=&#8220;#e8168a&#8220; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;10px&#8220; button_letter_spacing=&#8220;0.5px&#8220; button_font=&#8220;|600|||||||&#8220; button_use_icon=&#8220;off&#8220; background_layout=&#8220;dark&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; button_bg_color__hover_enabled=&#8220;on|hover&#8220; button_bg_color__hover=&#8220;#bf1272&#8243; button_bg_enable_color__hover=&#8220;on&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#f9ede1&#8243; custom_padding=&#8220;||40px||false|false&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|700|||||||&#8220; text_text_color=&#8220;#FFFFFF&#8220; text_font_size=&#8220;1.25rem&#8220; text_line_height=&#8220;2em&#8220; background_color=&#8220;#547c99&#8243; text_orientation=&#8220;center&#8220; custom_padding=&#8220;20px|20px|20px|20px|true|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<p>Niveau C1<br \/>3 Stunden\/Woche<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_line_height=&#8220;2em&#8220; header_5_font=&#8220;|700|||||||&#8220; header_5_text_color=&#8220;#1688be&#8220; header_5_font_size=&#8220;1.25rem&#8220; custom_padding=&#8220;10px|40px|10px|40px|false|true&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<p><strong>Vormittags und Nachmittagskurs<\/strong><\/p>\n<h5 style=\"padding-top: 25px;\">139\u20ac monatlich<\/h5>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;https:\/\/halkidonioplus.com\/de\/register\/griechischkurse-fuer-jugendliche-und-erwachsene-niveau-c1-kostenlose-testversion\/&#8220; button_text=&#8220;Kostenlose Testversion&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;20px&#8220; button_bg_color=&#8220;#e8168a&#8220; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;10px&#8220; button_letter_spacing=&#8220;0.5px&#8220; button_font=&#8220;|600|||||||&#8220; button_use_icon=&#8220;off&#8220; background_layout=&#8220;dark&#8220; global_colors_info=&#8220;{}&#8220; button_bg_color__hover_enabled=&#8220;on|hover&#8220; button_bg_color__hover=&#8220;#bf1272&#8243; button_bg_enable_color__hover=&#8220;on&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#f9ede1&#8243; custom_padding=&#8220;||40px||false|false&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|700|||||||&#8220; text_text_color=&#8220;#FFFFFF&#8220; text_font_size=&#8220;1.25rem&#8220; text_line_height=&#8220;2em&#8220; background_color=&#8220;#b29e2d&#8220; text_orientation=&#8220;center&#8220; custom_padding=&#8220;20px|20px|20px|20px|true|false&#8220; hover_enabled=&#8220;0&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<p>Niveau C2<br \/>3 Stunden\/Woche<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_line_height=&#8220;2em&#8220; header_5_font=&#8220;|700|||||||&#8220; header_5_text_color=&#8220;#1688be&#8220; header_5_font_size=&#8220;1.25rem&#8220; custom_padding=&#8220;10px|40px|10px|40px|false|true&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<p><strong>Vormittags und Nachmittagskurs<\/strong><\/p>\n<h5 style=\"padding-top: 25px;\">200\u20ac monatlich<\/h5>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;https:\/\/halkidonioplus.com\/de\/register\/griechischkurse-fuer-jugendliche-und-erwachsene-niveau-c2-kostenlose-testversion\/&#8220; button_text=&#8220;Kostenlose Testversion&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;20px&#8220; button_bg_color=&#8220;#e8168a&#8220; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;10px&#8220; button_letter_spacing=&#8220;0.5px&#8220; button_font=&#8220;|600|||||||&#8220; button_use_icon=&#8220;off&#8220; background_layout=&#8220;dark&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; button_bg_color__hover_enabled=&#8220;on|hover&#8220; button_bg_color__hover=&#8220;#bf1272&#8243; button_bg_enable_color__hover=&#8220;on&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;50px||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|600|||||||&#8220; text_text_color=&#8220;#FFFFFF&#8220; text_font_size=&#8220;1.5rem&#8220; text_line_height=&#8220;1.5em&#8220; background_color=&#8220;#1688be&#8220; custom_padding=&#8220;10px|20px|13px|20px|false|true&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]Griechisch Konversationskurse[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;40px||||false|false&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220; sticky_enabled=&#8220;0&#8243;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#f9ede1&#8243; custom_padding=&#8220;||40px||false|false&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|700|||||||&#8220; text_text_color=&#8220;#FFFFFF&#8220; text_font_size=&#8220;1.25rem&#8220; text_line_height=&#8220;2em&#8220; background_color=&#8220;#0eb1b2&#8243; text_orientation=&#8220;center&#8220; custom_padding=&#8220;20px|20px|20px|20px|true|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<p>Griechisch Konversationskurs I<br \/>2 Stunden\/Woche<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_line_height=&#8220;2em&#8220; header_5_font=&#8220;|700|||||||&#8220; header_5_text_color=&#8220;#1688be&#8220; header_5_font_size=&#8220;1.25rem&#8220; text_orientation=&#8220;center&#8220; custom_padding=&#8220;10px|40px|10px|40px|false|true&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<p style=\"line-height: 1.5em;\">Dieser Kurs wendet sich an Erwachsene, die die Niveaustufe A2-B2 erreicht haben<\/p>\n<h5 style=\"padding-top: 25px;\">99\u20ac monatlich<\/h5>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;https:\/\/halkidonioplus.com\/de\/register\/griechischkurse-fuer-jugendliche-und-erwachsene-konversationskurs-i-kostenlose-testversion\/&#8220; button_text=&#8220;Kostenlose Testversion&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;20px&#8220; button_bg_color=&#8220;#e8168a&#8220; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;10px&#8220; button_letter_spacing=&#8220;0.5px&#8220; button_font=&#8220;|600|||||||&#8220; button_use_icon=&#8220;off&#8220; background_layout=&#8220;dark&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; button_bg_color__hover_enabled=&#8220;on|hover&#8220; button_bg_color__hover=&#8220;#bf1272&#8243; button_bg_enable_color__hover=&#8220;on&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#f9ede1&#8243; custom_padding=&#8220;||40px||false|false&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|700|||||||&#8220; text_text_color=&#8220;#FFFFFF&#8220; text_font_size=&#8220;1.25rem&#8220; text_line_height=&#8220;2em&#8220; background_color=&#8220;#0eb1b2&#8243; text_orientation=&#8220;center&#8220; custom_padding=&#8220;20px|20px|20px|20px|true|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]Griechisch Konversationskurs II<br \/>\n2 Stunden\/Woche[\/et_pb_text][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_line_height=&#8220;2em&#8220; header_5_font=&#8220;|700|||||||&#8220; header_5_text_color=&#8220;#1688be&#8220; header_5_font_size=&#8220;1.25rem&#8220; text_orientation=&#8220;center&#8220; custom_padding=&#8220;10px|40px|10px|40px|false|true&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<p style=\"line-height: 1.5em;\">Dieser Kurs wendet sich an Erwachsene, die die Stufe B2-C2 erreicht haben<\/p>\n<h5 style=\"padding-top: 25px;\">99\u20ac monatlich<\/h5>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;https:\/\/halkidonioplus.com\/de\/register\/griechischkurse-fuer-jugendliche-und-erwachsene-konversationskurs-ii-kostenlose-testversion\/&#8220; button_text=&#8220;Kostenlose Testversion&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;20px&#8220; button_bg_color=&#8220;#e8168a&#8220; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;10px&#8220; button_letter_spacing=&#8220;0.5px&#8220; button_font=&#8220;|600|||||||&#8220; button_use_icon=&#8220;off&#8220; background_layout=&#8220;dark&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; button_bg_color__hover_enabled=&#8220;on|hover&#8220; button_bg_color__hover=&#8220;#bf1272&#8243; button_bg_enable_color__hover=&#8220;on&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;50px||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|600|||||||&#8220; text_text_color=&#8220;#FFFFFF&#8220; text_font_size=&#8220;1.5rem&#8220; text_line_height=&#8220;1.5em&#8220; background_color=&#8220;#1688be&#8220; custom_padding=&#8220;10px|20px|13px|20px|false|true&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]Griechisch f\u00fcr Business und Wirtschaft[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;40px||||false|false&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220; sticky_enabled=&#8220;0&#8243;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#f9ede1&#8243; custom_padding=&#8220;||40px||false|false&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;|700|||||||&#8220; text_text_color=&#8220;#FFFFFF&#8220; text_font_size=&#8220;1.25rem&#8220; text_line_height=&#8220;2em&#8220; background_color=&#8220;#476647&#8243; text_orientation=&#8220;center&#8220; custom_padding=&#8220;20px|20px|20px|20px|true|false&#8220; hover_enabled=&#8220;0&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<p>Business Greek language skills<br \/>2 Stunden\/Woche<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_line_height=&#8220;2em&#8220; header_5_font=&#8220;|700|||||||&#8220; header_5_text_color=&#8220;#1688be&#8220; header_5_font_size=&#8220;1.25rem&#8220; custom_padding=&#8220;10px|40px|10px|40px|false|true&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<p style=\"line-height: 1.5em;\">Der Kurs richtet sich an diejenige, die ihre Kommunikationskompetenz im Arbeitsplatz verbessern, sowie ihre Karriere f\u00f6rdern m\u00f6chten.<\/p>\n<h5 style=\"padding-top: 25px;\">199\u20ac monatlich<\/h5>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;https:\/\/halkidonioplus.com\/de\/register\/griechischkurse-fuer-jugendliche-und-erwachsene-business-greek-language-skills-kostenlose-testversion\/&#8220; button_text=&#8220;Kostenlose Testversion&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;20px&#8220; button_bg_color=&#8220;#e8168a&#8220; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;10px&#8220; button_letter_spacing=&#8220;0.5px&#8220; button_font=&#8220;|600|||||||&#8220; button_use_icon=&#8220;off&#8220; background_layout=&#8220;dark&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; button_bg_color__hover_enabled=&#8220;on|hover&#8220; button_bg_color__hover=&#8220;#bf1272&#8243; button_bg_enable_color__hover=&#8220;on&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; background_enable_color=&#8220;off&#8220; custom_padding=&#8220;||40px||false|false&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; custom_padding=&#8220;80px||||false|false&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]* Falls Sie sich nicht f\u00fcr eine Fortsetzung nach dem ersten Probeunterricht entscheiden, bestehen f\u00fcr Sie keine weiteren finanziellen Verpflichtungen. Falls Sie sich entscheiden fortzusetzen, wird der erste Probeunterricht in Ihre monatliche Zahlung einbezogen.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201c\u0392richst du auf gen Ithaka,so w\u00fcnsch dir eine lange Fahrt,voller Abenteuer und Erkenntnisse\u201d\u2014K.P.KavafisLernen Sie Griechisch einfach und effektiv. HalkidonioPlus bietet online Griechischkurse an und steht Ihnen zur Verf\u00fcgung, um Sie durch die griechische Sprache mit der griechischen Kultur und Geschichte vertraut zu machen. Bereits von Anfang an, sprechen, lesen, schreiben und kommunizieren die Lernenden in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":471,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-2134","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Griechischkurse f\u00fcr Jugendliche und Erwachsene - Halkidonio Plus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/halkidonioplus.com\/de\/griechischkurse-fuer-jugendliche-und-erwachsene\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Griechischkurse f\u00fcr Jugendliche und Erwachsene - Halkidonio Plus\" \/>\n<meta property=\"og:description\" content=\"\u201c\u0392richst du auf gen Ithaka,so w\u00fcnsch dir eine lange Fahrt,voller Abenteuer und Erkenntnisse\u201d\u2014K.P.KavafisLernen Sie Griechisch einfach und effektiv. HalkidonioPlus bietet online Griechischkurse an und steht Ihnen zur Verf\u00fcgung, um Sie durch die griechische Sprache mit der griechischen Kultur und Geschichte vertraut zu machen. Bereits von Anfang an, sprechen, lesen, schreiben und kommunizieren die Lernenden in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/halkidonioplus.com\/de\/griechischkurse-fuer-jugendliche-und-erwachsene\/\" \/>\n<meta property=\"og:site_name\" content=\"Halkidonio Plus\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-03T09:13:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/halkidonioplus.com\/wp-content\/uploads\/2021\/07\/about_us.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/halkidonioplus.com\\\/de\\\/griechischkurse-fuer-jugendliche-und-erwachsene\\\/\",\"url\":\"https:\\\/\\\/halkidonioplus.com\\\/de\\\/griechischkurse-fuer-jugendliche-und-erwachsene\\\/\",\"name\":\"Griechischkurse f\u00fcr Jugendliche und Erwachsene - Halkidonio Plus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/halkidonioplus.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/halkidonioplus.com\\\/de\\\/griechischkurse-fuer-jugendliche-und-erwachsene\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/halkidonioplus.com\\\/de\\\/griechischkurse-fuer-jugendliche-und-erwachsene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/halkidonioplus.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/about_us.jpg\",\"datePublished\":\"2021-07-22T09:40:02+00:00\",\"dateModified\":\"2024-08-03T09:13:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/halkidonioplus.com\\\/de\\\/griechischkurse-fuer-jugendliche-und-erwachsene\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/halkidonioplus.com\\\/de\\\/griechischkurse-fuer-jugendliche-und-erwachsene\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/halkidonioplus.com\\\/de\\\/griechischkurse-fuer-jugendliche-und-erwachsene\\\/#primaryimage\",\"url\":\"https:\\\/\\\/halkidonioplus.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/about_us.jpg\",\"contentUrl\":\"https:\\\/\\\/halkidonioplus.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/about_us.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"https:\\\/\\\/halkidonioplus.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/about_us.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/halkidonioplus.com\\\/de\\\/griechischkurse-fuer-jugendliche-und-erwachsene\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/halkidonioplus.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Griechischkurse f\u00fcr Jugendliche und Erwachsene\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/halkidonioplus.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/halkidonioplus.com\\\/de\\\/\",\"name\":\"Halkidonio Plus\",\"description\":\"Halkidonio Plus\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/halkidonioplus.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Griechischkurse f\u00fcr Jugendliche und Erwachsene - Halkidonio Plus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/halkidonioplus.com\/de\/griechischkurse-fuer-jugendliche-und-erwachsene\/","og_locale":"de_DE","og_type":"article","og_title":"Griechischkurse f\u00fcr Jugendliche und Erwachsene - Halkidonio Plus","og_description":"\u201c\u0392richst du auf gen Ithaka,so w\u00fcnsch dir eine lange Fahrt,voller Abenteuer und Erkenntnisse\u201d\u2014K.P.KavafisLernen Sie Griechisch einfach und effektiv. HalkidonioPlus bietet online Griechischkurse an und steht Ihnen zur Verf\u00fcgung, um Sie durch die griechische Sprache mit der griechischen Kultur und Geschichte vertraut zu machen. Bereits von Anfang an, sprechen, lesen, schreiben und kommunizieren die Lernenden in [&hellip;]","og_url":"https:\/\/halkidonioplus.com\/de\/griechischkurse-fuer-jugendliche-und-erwachsene\/","og_site_name":"Halkidonio Plus","article_modified_time":"2024-08-03T09:13:07+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/halkidonioplus.com\/wp-content\/uploads\/2021\/07\/about_us.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/halkidonioplus.com\/de\/griechischkurse-fuer-jugendliche-und-erwachsene\/","url":"https:\/\/halkidonioplus.com\/de\/griechischkurse-fuer-jugendliche-und-erwachsene\/","name":"Griechischkurse f\u00fcr Jugendliche und Erwachsene - Halkidonio Plus","isPartOf":{"@id":"https:\/\/halkidonioplus.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/halkidonioplus.com\/de\/griechischkurse-fuer-jugendliche-und-erwachsene\/#primaryimage"},"image":{"@id":"https:\/\/halkidonioplus.com\/de\/griechischkurse-fuer-jugendliche-und-erwachsene\/#primaryimage"},"thumbnailUrl":"https:\/\/halkidonioplus.com\/wp-content\/uploads\/2021\/07\/about_us.jpg","datePublished":"2021-07-22T09:40:02+00:00","dateModified":"2024-08-03T09:13:07+00:00","breadcrumb":{"@id":"https:\/\/halkidonioplus.com\/de\/griechischkurse-fuer-jugendliche-und-erwachsene\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/halkidonioplus.com\/de\/griechischkurse-fuer-jugendliche-und-erwachsene\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/halkidonioplus.com\/de\/griechischkurse-fuer-jugendliche-und-erwachsene\/#primaryimage","url":"https:\/\/halkidonioplus.com\/wp-content\/uploads\/2021\/07\/about_us.jpg","contentUrl":"https:\/\/halkidonioplus.com\/wp-content\/uploads\/2021\/07\/about_us.jpg","width":1000,"height":1000,"caption":"https:\/\/halkidonioplus.com\/wp-content\/uploads\/2021\/07\/about_us.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/halkidonioplus.com\/de\/griechischkurse-fuer-jugendliche-und-erwachsene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/halkidonioplus.com\/de\/"},{"@type":"ListItem","position":2,"name":"Griechischkurse f\u00fcr Jugendliche und Erwachsene"}]},{"@type":"WebSite","@id":"https:\/\/halkidonioplus.com\/de\/#website","url":"https:\/\/halkidonioplus.com\/de\/","name":"Halkidonio Plus","description":"Halkidonio Plus","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/halkidonioplus.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/halkidonioplus.com\/de\/wp-json\/wp\/v2\/pages\/2134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/halkidonioplus.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/halkidonioplus.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/halkidonioplus.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/halkidonioplus.com\/de\/wp-json\/wp\/v2\/comments?post=2134"}],"version-history":[{"count":16,"href":"https:\/\/halkidonioplus.com\/de\/wp-json\/wp\/v2\/pages\/2134\/revisions"}],"predecessor-version":[{"id":7050,"href":"https:\/\/halkidonioplus.com\/de\/wp-json\/wp\/v2\/pages\/2134\/revisions\/7050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/halkidonioplus.com\/de\/wp-json\/wp\/v2\/media\/471"}],"wp:attachment":[{"href":"https:\/\/halkidonioplus.com\/de\/wp-json\/wp\/v2\/media?parent=2134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}